{"id":1936,"date":"2022-08-29T08:53:46","date_gmt":"2022-08-29T06:53:46","guid":{"rendered":"https:\/\/sast-solutions.com\/blog-en\/?p=1936"},"modified":"2022-08-29T08:53:46","modified_gmt":"2022-08-29T06:53:46","slug":"interview-how-application-security-controls-automation-can-enable-business-performance","status":"publish","type":"post","link":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/","title":{"rendered":"Interview: How application security and controls automation can enable business performance"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1937 alignleft\" src=\"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh-300x181.jpg\" alt=\"SAST Blog: Interview: How Application Security And Controls Automation Can Enable Business Performance\" width=\"300\" height=\"181\" srcset=\"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh-300x181.jpg 300w, https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg 607w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> Expert Insights sat down with our <a href=\"https:\/\/pathlock.com\/\" target=\"_blank\" rel=\"noopener\">Pathlock<\/a>\u2019s Chief Marketing Officer, Mike Puterbaugh, in an exclusive interview to discuss how organizations can leverage application security and controls automation not only to improve their resilience against cyberthreats, but also to enable business performance.<\/p>\n<p>Read the full interview at:\u00a0<a href=\"https:\/\/lnkd.in\/gKPZxqZM\" target=\"_blank\" rel=\"noopener\" data-attribute-index=\"5\">https:\/\/lnkd.in\/gKPZxqZM<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expert Insights sat down with our Pathlock\u2019s Chief Marketing Officer, Mike Puterbaugh, in an exclusive interview to discuss how organizations can leverage application security and controls automation not only to improve their resilience against cyberthreats, but also to enable business performance. Read the full interview at:\u00a0https:\/\/lnkd.in\/gKPZxqZM &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[6],"tags":[25,156,68,80,103],"class_list":["post-1936","post","type-post","status-publish","format-aside","hentry","category-sap-security","tag-cyber-attack","tag-cyber-security","tag-sap-authorizations","tag-sap-security","tag-sod","post_format-post-format-aside"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Application security &amp; controls automation by Pathlock<\/title>\n<meta name=\"description\" content=\"Read the exclusive interview on how application security and control automation improves business performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Application security &amp; controls automation by Pathlock\" \/>\n<meta property=\"og:description\" content=\"Read the exclusive interview on how application security and control automation improves business performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/\" \/>\n<meta property=\"og:site_name\" content=\"SAST BLOG\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-29T06:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"securityblog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Application security &amp; controls automation by Pathlock\" \/>\n<meta name=\"twitter:description\" content=\"Read the exclusive interview on how application security and control automation improves business performance.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"securityblog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/\"},\"author\":{\"name\":\"securityblog\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#\\\/schema\\\/person\\\/cd70e3749cca136a7e8a37dc1d3cfc26\"},\"headline\":\"Interview: How application security and controls automation can enable business performance\",\"datePublished\":\"2022-08-29T06:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/\"},\"wordCount\":64,\"publisher\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mike-Puterbaugh-300x181.jpg\",\"keywords\":[\"Cyber Attack\",\"Cyber Security\",\"SAP Authorizations\",\"SAP Security\",\"SoD\"],\"articleSection\":[\"SAP Security\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/\",\"url\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/\",\"name\":\"Application security & controls automation by Pathlock\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mike-Puterbaugh-300x181.jpg\",\"datePublished\":\"2022-08-29T06:53:46+00:00\",\"description\":\"Read the exclusive interview on how application security and control automation improves business performance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mike-Puterbaugh.jpg\",\"contentUrl\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mike-Puterbaugh.jpg\",\"width\":607,\"height\":367,\"caption\":\"SAST Blog: Interview: How Application Security And Controls Automation Can Enable Business Performance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/2022\\\/08\\\/29\\\/interview-how-application-security-controls-automation-can-enable-business-performance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview: How application security and controls automation can enable business performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#website\",\"url\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/\",\"name\":\"SAST BLOG\",\"description\":\"SAP Security &amp; Compliance\",\"publisher\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#organization\",\"name\":\"SAST BLOG\",\"url\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sast-solutions-logo.png\",\"contentUrl\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sast-solutions-logo.png\",\"width\":358,\"height\":155,\"caption\":\"SAST BLOG\"},\"image\":{\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sast-solutions.com\\\/blog-en\\\/#\\\/schema\\\/person\\\/cd70e3749cca136a7e8a37dc1d3cfc26\",\"name\":\"securityblog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Application security & controls automation by Pathlock","description":"Read the exclusive interview on how application security and control automation improves business performance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/","og_locale":"en_US","og_type":"article","og_title":"Application security & controls automation by Pathlock","og_description":"Read the exclusive interview on how application security and control automation improves business performance.","og_url":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/","og_site_name":"SAST BLOG","article_published_time":"2022-08-29T06:53:46+00:00","og_image":[{"width":607,"height":367,"url":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg","type":"image\/jpeg"}],"author":"securityblog","twitter_card":"summary_large_image","twitter_title":"Application security & controls automation by Pathlock","twitter_description":"Read the exclusive interview on how application security and control automation improves business performance.","twitter_image":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg","twitter_misc":{"Written by":"securityblog","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#article","isPartOf":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/"},"author":{"name":"securityblog","@id":"https:\/\/sast-solutions.com\/blog-en\/#\/schema\/person\/cd70e3749cca136a7e8a37dc1d3cfc26"},"headline":"Interview: How application security and controls automation can enable business performance","datePublished":"2022-08-29T06:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/"},"wordCount":64,"publisher":{"@id":"https:\/\/sast-solutions.com\/blog-en\/#organization"},"image":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#primaryimage"},"thumbnailUrl":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh-300x181.jpg","keywords":["Cyber Attack","Cyber Security","SAP Authorizations","SAP Security","SoD"],"articleSection":["SAP Security"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/","url":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/","name":"Application security & controls automation by Pathlock","isPartOf":{"@id":"https:\/\/sast-solutions.com\/blog-en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#primaryimage"},"image":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#primaryimage"},"thumbnailUrl":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh-300x181.jpg","datePublished":"2022-08-29T06:53:46+00:00","description":"Read the exclusive interview on how application security and control automation improves business performance.","breadcrumb":{"@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#primaryimage","url":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg","contentUrl":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2022\/08\/Mike-Puterbaugh.jpg","width":607,"height":367,"caption":"SAST Blog: Interview: How Application Security And Controls Automation Can Enable Business Performance"},{"@type":"BreadcrumbList","@id":"https:\/\/sast-solutions.com\/blog-en\/2022\/08\/29\/interview-how-application-security-controls-automation-can-enable-business-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sast-solutions.com\/blog-en\/"},{"@type":"ListItem","position":2,"name":"Interview: How application security and controls automation can enable business performance"}]},{"@type":"WebSite","@id":"https:\/\/sast-solutions.com\/blog-en\/#website","url":"https:\/\/sast-solutions.com\/blog-en\/","name":"SAST BLOG","description":"SAP Security &amp; Compliance","publisher":{"@id":"https:\/\/sast-solutions.com\/blog-en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sast-solutions.com\/blog-en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sast-solutions.com\/blog-en\/#organization","name":"SAST BLOG","url":"https:\/\/sast-solutions.com\/blog-en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sast-solutions.com\/blog-en\/#\/schema\/logo\/image\/","url":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2021\/03\/sast-solutions-logo.png","contentUrl":"https:\/\/sast-solutions.com\/blog-en\/wp-content\/uploads\/2021\/03\/sast-solutions-logo.png","width":358,"height":155,"caption":"SAST BLOG"},"image":{"@id":"https:\/\/sast-solutions.com\/blog-en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sast-solutions.com\/blog-en\/#\/schema\/person\/cd70e3749cca136a7e8a37dc1d3cfc26","name":"securityblog"}]}},"_links":{"self":[{"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/posts\/1936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/comments?post=1936"}],"version-history":[{"count":4,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/posts\/1936\/revisions"}],"predecessor-version":[{"id":1941,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/posts\/1936\/revisions\/1941"}],"wp:attachment":[{"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/media?parent=1936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/categories?post=1936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sast-solutions.com\/blog-en\/wp-json\/wp\/v2\/tags?post=1936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}